{"id":1316,"date":"2025-10-04T21:50:42","date_gmt":"2025-10-04T21:50:42","guid":{"rendered":"https:\/\/mychoice.social\/index.php\/product\/m-4xl-printemps-ete-haut-pour-femme-2024-nouvelle-mode\/"},"modified":"2025-10-04T21:50:42","modified_gmt":"2025-10-04T21:50:42","slug":"m-4xl-printemps-ete-haut-pour-femme-2024-nouvelle-mode","status":"publish","type":"product","link":"https:\/\/mychoice.social\/index.php\/product\/m-4xl-printemps-ete-haut-pour-femme-2024-nouvelle-mode\/","title":{"rendered":"M-4XL printemps \u00e9t\u00e9 haut pour femme 2024 nouvelle mode"},"content":{"rendered":"<div class=\"title--wrap--NWOaiSp\">\n<div class=\"title--text--Otu0bLr\" style=\"margin: 0px;padding: 0px;cursor: default;height: 56px\">\n<h2 class=\"title--title--O6xcB1q\" style=\"font-size: 24px;margin: 0px\">D\u00e9tails<\/h2>\n<\/div>\n<\/div>\n<ul class=\"specification--list--GZuXzRX\">\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Type de fermeture<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Aucun\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Aucun<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Si l&#8217;ouverture compl\u00e8te<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Non\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Non<\/span><\/div>\n<\/div>\n<\/li>\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Chimique Hign-concern\u00e9<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Aucun\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Aucun<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Artisanat du tissage<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Tat\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Tat<\/span><\/div>\n<\/div>\n<\/li>\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Mod\u00e8les de v\u00eatements<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Droit\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Droit<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Mod\u00e8les de robe<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Pull\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Pull<\/span><\/div>\n<\/div>\n<\/li>\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Saison<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Printemps\/\u00c9t\u00e9\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Printemps\/\u00c9t\u00e9<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Forme de combinaison<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Ensemble d\u2019une seule pi\u00e8ce\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Ensemble d\u2019une seule pi\u00e8ce<\/span><\/div>\n<\/div>\n<\/li>\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Composition mat\u00e9rielle<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Fibre synth\u00e9tique\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Fibre synth\u00e9tique<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">\u00c2ge<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"MIDDLE AGE\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">MIDDLE AGE<\/span><\/div>\n<\/div>\n<\/li>\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">\u00c9paisseur<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Norme\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Norme<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Type de Chemises<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"CHEMISES D\u00c9CONTRACT\u00c9ES\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">CHEMISES D\u00c9CONTRACT\u00c9ES<\/span><\/div>\n<\/div>\n<\/li>\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Num\u00e9ro de Mod\u00e8le<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"XY0514\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">XY0514<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Type de tissu<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Mousseline\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Mousseline<\/span><\/div>\n<\/div>\n<\/li>\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">D\u00e9coration<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Appliques\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Appliques<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Mat\u00e9riau<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"AC\u00c9TATE,POLYESTER\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">AC\u00c9TATE,POLYESTER<\/span><\/div>\n<\/div>\n<\/li>\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Longueur de Manche (cm)<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Moiti\u00e9\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Moiti\u00e9<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Sexe<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"WOMEN\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">WOMEN<\/span><\/div>\n<\/div>\n<\/li>\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Nom de marque<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"dingaozlz\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">dingaozlz<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Style de manche<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"r\u00e9gulier\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">r\u00e9gulier<\/span><\/div>\n<\/div>\n<\/li>\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Longueur de V\u00eatement<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"r\u00e9gulier\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">r\u00e9gulier<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Collier<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"STAND\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">STAND<\/span><\/div>\n<\/div>\n<\/li>\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Type de Motif<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Solide\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Solide<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Style<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Cor\u00e9en\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Cor\u00e9en<\/span><\/div>\n<\/div>\n<\/li>\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">\u00c9lasticit\u00e9<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Non Extensible\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Non Extensible<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Origine<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"CN (Origine)\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">CN (Origine)<\/span><\/div>\n<\/div>\n<\/li>\n<li class=\"specification--line--IXeRJI7\" style=\"margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: unset;padding: 0px\">\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">CN<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"Guangdong\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Guangdong<\/span><\/div>\n<\/div>\n<div class=\"specification--prop--Jh28bKu\" style=\"margin: 0px;padding: 0px;float: left;line-height: 28px;max-width: 50%;position: relative;width: 426px\">\n<div class=\"specification--title--SfH3sA8\" style=\"margin: 0px;padding: 16px;line-height: 20px;width: 174px\"><span style=\"margin: 0px;padding: 0px;line-height: 20px\">Type adapt\u00e9<\/span><\/div>\n<div class=\"specification--desc--Dxx6W0W\" title=\"R\u00e8glement Ajustement\" style=\"margin: 0px;padding: 16px;line-height: 20px;flex: 1 1 0%\"><span data-spm-anchor-id=\"a2g0o.detail.0.i16.12deTWtRTWtR6n\" style=\"margin: 0px;padding: 0px;line-height: 20px\">R\u00e8glement Ajustement<\/span><\/div>\n<\/div>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><br data-mce-bogus=\"1\"><\/p>\n","protected":false},"featured_media":1315,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default"},"product_brand":[],"product_cat":[27,26],"product_tag":[],"class_list":{"0":"post-1316","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-holiday","7":"product_cat-tops","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-external"},"uagb_featured_image_src":{"full":["https:\/\/mychoice.social\/wp-content\/uploads\/2025\/10\/S9e3a14af8b8d4b32a4d20076a2fbb311K.jpg_350x350.avif",350,350,false],"thumbnail":["https:\/\/mychoice.social\/wp-content\/uploads\/2025\/10\/S9e3a14af8b8d4b32a4d20076a2fbb311K.jpg_350x350-150x150.avif",150,150,true],"medium":["https:\/\/mychoice.social\/wp-content\/uploads\/2025\/10\/S9e3a14af8b8d4b32a4d20076a2fbb311K.jpg_350x350-300x300.avif",300,300,true],"medium_large":["https:\/\/mychoice.social\/wp-content\/uploads\/2025\/10\/S9e3a14af8b8d4b32a4d20076a2fbb311K.jpg_350x350.avif",350,350,false],"large":["https:\/\/mychoice.social\/wp-content\/uploads\/2025\/10\/S9e3a14af8b8d4b32a4d20076a2fbb311K.jpg_350x350.avif",350,350,false],"1536x1536":["https:\/\/mychoice.social\/wp-content\/uploads\/2025\/10\/S9e3a14af8b8d4b32a4d20076a2fbb311K.jpg_350x350.avif",350,350,false],"2048x2048":["https:\/\/mychoice.social\/wp-content\/uploads\/2025\/10\/S9e3a14af8b8d4b32a4d20076a2fbb311K.jpg_350x350.avif",350,350,false],"woocommerce_thumbnail":["https:\/\/mychoice.social\/wp-content\/uploads\/2025\/10\/S9e3a14af8b8d4b32a4d20076a2fbb311K.jpg_350x350-300x300.avif",300,300,true],"woocommerce_single":["https:\/\/mychoice.social\/wp-content\/uploads\/2025\/10\/S9e3a14af8b8d4b32a4d20076a2fbb311K.jpg_350x350.avif",350,350,false],"woocommerce_gallery_thumbnail":["https:\/\/mychoice.social\/wp-content\/uploads\/2025\/10\/S9e3a14af8b8d4b32a4d20076a2fbb311K.jpg_350x350-100x100.avif",100,100,true]},"uagb_author_info":{"display_name":"MyChoice","author_link":"https:\/\/mychoice.social\/index.php\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mychoice.social\/index.php\/wp-json\/wp\/v2\/product\/1316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mychoice.social\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mychoice.social\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mychoice.social\/index.php\/wp-json\/wp\/v2\/comments?post=1316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mychoice.social\/index.php\/wp-json\/wp\/v2\/media\/1315"}],"wp:attachment":[{"href":"https:\/\/mychoice.social\/index.php\/wp-json\/wp\/v2\/media?parent=1316"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mychoice.social\/index.php\/wp-json\/wp\/v2\/product_brand?post=1316"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mychoice.social\/index.php\/wp-json\/wp\/v2\/product_cat?post=1316"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mychoice.social\/index.php\/wp-json\/wp\/v2\/product_tag?post=1316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}